{"id":44,"count":3,"description":"","link":"https:\/\/www.viaggioemozioneacavallo.com\/en\/category\/ideas-for-riding-holidays\/","name":"Ideas for riding holidays","slug":"ideas-for-riding-holidays","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ideas for riding holidays Archivi - Journey - emotion on horseback<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.viaggioemozioneacavallo.com\/en\/category\/ideas-for-riding-holidays\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ideas for riding holidays Archivi - Journey - emotion on horseback\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.viaggioemozioneacavallo.com\/en\/category\/ideas-for-riding-holidays\/\" \/>\n<meta property=\"og:site_name\" content=\"Journey - emotion on horseback\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.viaggioemozioneacavallo.com\/en\/category\/ideas-for-riding-holidays\/\",\"url\":\"https:\/\/www.viaggioemozioneacavallo.com\/en\/category\/ideas-for-riding-holidays\/\",\"name\":\"Ideas for riding holidays Archivi - Journey - emotion on horseback\",\"isPartOf\":{\"@id\":\"https:\/\/www.viaggioemozioneacavallo.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.viaggioemozioneacavallo.com\/en\/category\/ideas-for-riding-holidays\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.viaggioemozioneacavallo.com\/en\/category\/ideas-for-riding-holidays\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.viaggioemozioneacavallo.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ideas for riding holidays\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.viaggioemozioneacavallo.com\/#website\",\"url\":\"https:\/\/www.viaggioemozioneacavallo.com\/\",\"name\":\"Journey - emotion on horseback\",\"description\":\"Horse riding holidays in Italy and abroad : are we leaving?\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.viaggioemozioneacavallo.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ideas for riding holidays Archivi - Journey - emotion on horseback","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.viaggioemozioneacavallo.com\/en\/category\/ideas-for-riding-holidays\/","og_locale":"en_US","og_type":"article","og_title":"Ideas for riding holidays Archivi - Journey - emotion on horseback","og_url":"https:\/\/www.viaggioemozioneacavallo.com\/en\/category\/ideas-for-riding-holidays\/","og_site_name":"Journey - emotion on horseback","twitter_card":"summary","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.viaggioemozioneacavallo.com\/en\/category\/ideas-for-riding-holidays\/","url":"https:\/\/www.viaggioemozioneacavallo.com\/en\/category\/ideas-for-riding-holidays\/","name":"Ideas for riding holidays Archivi - Journey - emotion on horseback","isPartOf":{"@id":"https:\/\/www.viaggioemozioneacavallo.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.viaggioemozioneacavallo.com\/en\/category\/ideas-for-riding-holidays\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.viaggioemozioneacavallo.com\/en\/category\/ideas-for-riding-holidays\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.viaggioemozioneacavallo.com\/en\/"},{"@type":"ListItem","position":2,"name":"Ideas for riding holidays"}]},{"@type":"WebSite","@id":"https:\/\/www.viaggioemozioneacavallo.com\/#website","url":"https:\/\/www.viaggioemozioneacavallo.com\/","name":"Journey - emotion on horseback","description":"Horse riding holidays in Italy and abroad : are we leaving?","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.viaggioemozioneacavallo.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.viaggioemozioneacavallo.com\/en\/wp-json\/wp\/v2\/categories\/44"}],"collection":[{"href":"https:\/\/www.viaggioemozioneacavallo.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.viaggioemozioneacavallo.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.viaggioemozioneacavallo.com\/en\/wp-json\/wp\/v2\/posts?categories=44"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}